{"id":56372,"date":"2022-12-08T15:20:34","date_gmt":"2022-12-08T17:20:34","guid":{"rendered":"http:\/\/www2.comunitaria.com.br\/?p=56372"},"modified":"2022-12-08T15:20:34","modified_gmt":"2022-12-08T17:20:34","slug":"cotrifred-realiza-planejamento-estrategico-para-2023","status":"publish","type":"post","link":"https:\/\/www2.comunitaria.com.br\/en\/cotrifred-realiza-planejamento-estrategico-para-2023\/","title":{"rendered":"Cotrifred realiza Planejamento Estrat\u00e9gico para 2023"},"content":{"rendered":"<p>Pensando nas a\u00e7\u00f5es da cooperativa para o pr\u00f3ximo ano, durante os dias 02 e 03 de dezembro, a dire\u00e7\u00e3o da Cotrifred, juntamente com membros do conselho e gerentes, estiveram participando do Planejamento Estrat\u00e9gico 2023. O momento aconteceu em Chapec\u00f3 \u2013 SC e foi oportuno para planejar os pr\u00f3ximos passos da Cotrifred.<br \/>\nVisando o crescimento da cooperativa, inova\u00e7\u00f5es, investimentos e melhorias foram pauta do planejamento deste ano, onde foram tra\u00e7adas novas metas e a\u00e7\u00f5es para os segmentos da Cotrifred.<br \/>\nAs lideran\u00e7as dos principais setores da cooperativa estiveram reunidas para discutir, analisar e planejar novas a\u00e7\u00f5es para seus respectivos setores, englobando supermercado, agropecu\u00e1ria, latic\u00ednios, gr\u00e3os, f\u00e1brica de ra\u00e7\u00e3o, comunica\u00e7\u00e3o e recursos humanos.<br \/>\nCom o intu\u00eddo de engajar a equipe, os participantes tamb\u00e9m participaram de uma palestra sobre \u201cA import\u00e2ncia do planejamento estrat\u00e9gico: Cen\u00e1rios, desafios e oportunidades\u201d ministrada pelo palestrante, professor e empreendedor, Jean Matos, que refor\u00e7ou sobre a import\u00e2ncia do planejamento e os desafios do mesmo para o crescimento e desenvolvimento de entidades.<br \/>\nNo planejamento do ano anterior, a cooperativa havia tra\u00e7ado a meta de chegar a R$ 10 milh\u00f5es em resultado, que possibilitaria uma maior distribui\u00e7\u00e3o aos associados, al\u00e9m de proporcionar a realiza\u00e7\u00e3o de mais investimentos nas unidades.<br \/>\nO Planejamento Estrat\u00e9gico foi essencial para que a Cotrifred pudesse alcan\u00e7ar as metas e objetivos tra\u00e7ados para 2022. Agora, com o resultado alcan\u00e7ado, o planejamento para 2023 torna-se ainda mais importante e desafiador.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pensando nas a\u00e7\u00f5es da cooperativa para o pr\u00f3ximo ano, durante os dias 02 e 03 de dezembro, a dire\u00e7\u00e3o da Cotrifred, juntamente com membros do conselho e gerentes, estiveram participando do Planejamento Estrat\u00e9gico 2023. O momento aconteceu em Chapec\u00f3 \u2013 SC e foi oportuno para planejar os pr\u00f3ximos passos da Cotrifred. Visando o crescimento da<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/www2.comunitaria.com.br\/en\/cotrifred-realiza-planejamento-estrategico-para-2023\/\" title=\"Read More\"> <span class=\"button\">Read More<\/span><\/a><\/div>","protected":false},"author":2,"featured_media":56373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[42,33],"tags":[],"class_list":["post-56372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fred-west","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/56372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/comments?post=56372"}],"version-history":[{"count":0,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/56372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media\/56373"}],"wp:attachment":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media?parent=56372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/categories?post=56372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/tags?post=56372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}