{"id":44607,"date":"2021-01-07T14:27:45","date_gmt":"2021-01-07T16:27:45","guid":{"rendered":"http:\/\/www2.comunitaria.com.br\/?p=44607"},"modified":"2021-01-07T14:27:45","modified_gmt":"2021-01-07T16:27:45","slug":"medo-do-desemprego-e-crescente-entre-os-brasileiros","status":"publish","type":"post","link":"https:\/\/www2.comunitaria.com.br\/en\/medo-do-desemprego-e-crescente-entre-os-brasileiros\/","title":{"rendered":"Medo do desemprego \u00e9 crescente entre os brasileiros"},"content":{"rendered":"<p>O medo de perder o emprego \u00e9 crescente entre os brasileiros. A preocupa\u00e7\u00e3o \u00e9 ainda mais intensa entre mulheres, jovens com idade entre 16 e 24 anos, profissionais com baixa escolaridade e moradores de periferias. \u00c9 o que aponta a pesquisa \u00cdndice do Medo do Desemprego, divulgada nesta quarta-feira,6, pela Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1398121&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1398121&amp;o=node\"><\/p>\n<p>Segundo o estudo, o \u00edndice ficou em 57,1 pontos, na medi\u00e7\u00e3o feita em dezembro de 2020 \u2013 n\u00famero que se encontra acima da m\u00e9dia hist\u00f3rica de 50,2 pontos. <em>\u201cNo trimestre, o indicador subiu 2,1 pontos na compara\u00e7\u00e3o com setembro do ano passado e est\u00e1 um ponto acima do registrado em dezembro de 2019\u201d,<\/em> disse a CNI.<\/p>\n<p>Quando o recorte abrange o p\u00fablico feminino, o indicador (que mede o medo de perder o emprego) fica ainda maior, chegando a 64,2 pontos. Entre os homens, o \u00edndice est\u00e1 em 49,4 pontos. Nos dois casos a CNI identificou aumento do medo do desemprego, na compara\u00e7\u00e3o com setembro.<\/p>\n<p>Levando em conta o grau de instru\u00e7\u00e3o dos entrevistados, o perfil que apresentou n\u00edvel maior de medo \u00e9 o de pessoas com grau de instru\u00e7\u00e3o inferior ao ensino m\u00e9dio completo, ficando em 59,1 pontos entre os que estudaram at\u00e9 a 4\u00aa s\u00e9rie da educa\u00e7\u00e3o fundamental, e em 59,2 pontos entre os com instru\u00e7\u00e3o entre a 5\u00aa e a 8\u00aa s\u00e9rie.<\/p>\n<p><em>\u201cO temor tamb\u00e9m cresceu entre os entrevistados com educa\u00e7\u00e3o superior\u201d,<\/em> afirma a CNI. Nesse caso, o \u00edndice passou de 50,1 pontos em setembro para 54,7 pontos em dezembro. <em>\u201cAinda assim, esse grupo da popula\u00e7\u00e3o [\u00e9 o que] apresenta o menor \u00edndice de medo do desemprego entre os estratos por grau de instru\u00e7\u00e3o\u201d<\/em>, explica a entidade.<\/p>\n<p>Moradores das periferias tamb\u00e9m est\u00e3o entre os que apresentaram maior crescimento no \u00cdndice do Medo do Desemprego, passando dos 55,9 pontos de setembro para 65,5 pontos em dezembro. Tendo como recorte os residentes nas capitais, o \u00edndice ficou em 57,5 pontos . J\u00e1 os moradores das cidades do interior registraram um \u00edndice de 55,2 pontos.<\/p>\n<h4>Satisfa\u00e7\u00e3o com a vida<\/h4>\n<p>O levantamento apresentado pela CNI mede tamb\u00e9m o \u00cdndice de Satisfa\u00e7\u00e3o com a Vida (ISV). Este \u00edndice alcan\u00e7ou 70,2 pontos em dezembro de 2020, ficando acima da sua m\u00e9dia hist\u00f3rica de 69,6 pontos. De acordo com a CNI, isso n\u00e3o ocorria desde 2014.&nbsp;<\/p>\n<p>Para o gerente-executivo de Economia da CNI, Renato da Fonseca, essa melhora pode estar relacionada \u201ctanto \u00e0 percep\u00e7\u00e3o, no in\u00edcio de dezembro, de melhora da crise sanit\u00e1ria e econ\u00f4mica, como ao aux\u00edlio emergencial que proveu maior seguran\u00e7a econ\u00f4mica \u00e0s fam\u00edlias de baixa renda\u201d.<\/p>\n<p>Na avalia\u00e7\u00e3o da CNI, o aumento deste \u00edndice foi maior entre os entrevistados com renda familiar at\u00e9 dois sal\u00e1rios m\u00ednimos. <em>\u201cMas, mesmo assim, esse grupo apresenta o menor \u00edndice\u201d, complementa a CNI, ressaltando que a satisfa\u00e7\u00e3o \u201ccresce na medida em que aumentam a renda familiar e o grau de instru\u00e7\u00e3o do entrevistado\u201d.<\/em><\/p>\n<p>A satisfa\u00e7\u00e3o com a vida \u00e9 maior entre os mais jovens. <em>\u201cO \u00edndice cai de 72,8 pontos, entre os entrevistados com 16 anos a 24 anos de idade, para 68,9 pontos entre os com 55 anos ou mais\u201d.<\/em><\/p>\n<p>Para fazer esse levantamento, a CNI entrevistou duas mil pessoas em 126 munic\u00edpios, entre 5 e 8 de dezembro. As entrevistas foram feitas pelo Ibope Intelig\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<p><em>*Ag\u00eancia Brasil&nbsp;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O medo de perder o emprego \u00e9 crescente entre os brasileiros. A preocupa\u00e7\u00e3o \u00e9 ainda mais intensa entre mulheres, jovens com idade entre 16 e 24 anos, profissionais com baixa&#8230;<\/p>","protected":false},"author":2,"featured_media":44609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[33],"tags":[1926,1153,4691,5211],"class_list":["post-44607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-desemprego","tag-desempregonobrasil","tag-medododesemprego"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/44607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/comments?post=44607"}],"version-history":[{"count":0,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/44607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media\/44609"}],"wp:attachment":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media?parent=44607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/categories?post=44607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/tags?post=44607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}