{"id":42740,"date":"2020-10-02T15:46:13","date_gmt":"2020-10-02T17:46:13","guid":{"rendered":"http:\/\/www2.comunitaria.com.br\/?p=42740"},"modified":"2020-10-02T15:46:13","modified_gmt":"2020-10-02T17:46:13","slug":"aplicativo-do-distanciamento-controlado-facilita-consulta-das-bandeiras","status":"publish","type":"post","link":"https:\/\/www2.comunitaria.com.br\/en\/aplicativo-do-distanciamento-controlado-facilita-consulta-das-bandeiras\/","title":{"rendered":"Aplicativo do Distanciamento Controlado facilita consulta das bandeiras"},"content":{"rendered":"<p>O governo do Estado lan\u00e7ou um aplicativo de celular que permite acompanhar, em tempo real, a cor da bandeira dos munic\u00edpios conforme o mapa do Distanciamento Controlado.&nbsp;O servi\u00e7o est\u00e1 dispon\u00edvel para sistema Android e iOS.<\/p>\n<p>Por meio do aplicativo, o cidad\u00e3o ter\u00e1 acesso a informa\u00e7\u00f5es sobre o funcionamento do modelo e os crit\u00e9rios usados para definir a cor da bandeira de cada regi\u00e3o (amarela, laranja, vermelha ou preta), a partir de indicadores que medem o avan\u00e7o do v\u00edrus e a capacidade de atendimento do sistema de sa\u00fade.<\/p>\n<p>Desenvolvida por iniciativa da Secretaria de Comunica\u00e7\u00e3o e do Comit\u00ea de Dados no enfrentamento da Covid-19, a plataforma orienta tamb\u00e9m como as associa\u00e7\u00f5es regionais de munic\u00edpios podem buscar a cogest\u00e3o (que permite adotar protocolos menos restritivos \u00e0 classifica\u00e7\u00e3o de risco definida a cada semana).<\/p>\n<p>O app permite acessar os protocolos e limites de ocupa\u00e7\u00e3o para diferentes atividades econ\u00f4micas e re\u00fane informa\u00e7\u00f5es das a\u00e7\u00f5es do governo no enfrentamento da Covid-19. \u201cTrata-se de mais um recurso de comunica\u00e7\u00e3o direta com a popula\u00e7\u00e3o no sentido de informar sobre a situa\u00e7\u00e3o da pandemia em cada cidade\u201d, explica a secret\u00e1ria de Comunica\u00e7\u00e3o, T\u00e2nia Moreira.<\/p>\n<p>Em vigor desde o in\u00edcio do m\u00eas de maio, o modelo de Distanciamento Controlado j\u00e1 se aproxima da 22\u00aa semana de atualiza\u00e7\u00e3o do mapa. O modelo monitora 11 indicadores que acompanham, entre outros, o n\u00famero de leitos de UTI ocupados, os casos de interna\u00e7\u00e3o por Covid-19 e de outras doen\u00e7as respirat\u00f3rias graves, os novos diagn\u00f3sticos da doen\u00e7a e a capacidade instalada em cada regi\u00e3o e macrorregi\u00e3o do Estado.<\/p>\n<p><sub><em>T*S<\/em><\/sub><sub><em>ecom&nbsp;<\/em><\/sub><\/p>","protected":false},"excerpt":{"rendered":"<p>O governo do Estado lan\u00e7ou um aplicativo de celular que permite acompanhar, em tempo real, a cor da bandeira dos munic\u00edpios conforme o mapa do Distanciamento Controlado.&nbsp;O servi\u00e7o est\u00e1 dispon\u00edvel&#8230;<\/p>","protected":false},"author":2,"featured_media":42742,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[46,33,37],"tags":[],"class_list":["post-42740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-noticias","category-saude"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/42740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/comments?post=42740"}],"version-history":[{"count":0,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/42740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media\/42742"}],"wp:attachment":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media?parent=42740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/categories?post=42740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/tags?post=42740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}