{"id":18317,"date":"2016-05-10T10:18:11","date_gmt":"2016-05-10T12:18:11","guid":{"rendered":"http:\/\/www2.comunitaria.com.br\/?p=18317"},"modified":"2016-05-10T10:18:11","modified_gmt":"2016-05-10T12:18:11","slug":"quatro-homens-arrombam-supermercado-em-erval-seco","status":"publish","type":"post","link":"https:\/\/www2.comunitaria.com.br\/en\/quatro-homens-arrombam-supermercado-em-erval-seco\/","title":{"rendered":"Quatro homens arrombam supermercado em Erval Seco"},"content":{"rendered":"<p style=\"text-align: justify;\">Quatro homens armados e encapuzados arrombaram o supermercado da Cooperativa A1, em Erval Seco, na madrugada de segunda-feira, dia 09. Portando duas armas, os indiv\u00edduos chegaram em uma caminhonete branca por volta das 02h40min e derrubaram o port\u00e3o de acesso do estacionamento. Eles ent\u00e3o arrombaram a porta de entrada do mercado e levaram certa quantia de dinheiro que havia no cofre.<\/p>\n<p style=\"text-align: justify;\">Os homens fugiram para o interior do munic\u00edpio, em dire\u00e7\u00e3o a comunidade Lajeado Grande. A pol\u00edcia investiga o caso e analisa as imagens das c\u00e2meras de monitoramento do estabelecimento.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Com informa\u00e7\u00f5es R\u00e1dio Nativa FM<\/strong><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Quatro homens armados e encapuzados arrombaram o supermercado da Cooperativa A1, em Erval Seco, na madrugada de segunda-feira, dia 09. Portando duas armas, os indiv\u00edduos chegaram em uma caminhonete branca&#8230;<\/p>","protected":false},"author":2,"featured_media":18318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[33,36,43],"tags":[631,232,177,85,1426],"class_list":["post-18317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policia","category-regiao","tag-arrombamento","tag-erval-seco","tag-policia-2","tag-roubo","tag-supermercado"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/18317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/comments?post=18317"}],"version-history":[{"count":0,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/18317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media\/18318"}],"wp:attachment":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media?parent=18317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/categories?post=18317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/tags?post=18317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}