{"id":11549,"date":"2015-11-26T15:44:33","date_gmt":"2015-11-26T17:44:33","guid":{"rendered":"http:\/\/www2.comunitaria.com.br\/?p=11549"},"modified":"2015-11-26T15:55:59","modified_gmt":"2015-11-26T17:55:59","slug":"relatorio-aponta-desigualdade-global-entre-generos","status":"publish","type":"post","link":"https:\/\/www2.comunitaria.com.br\/en\/relatorio-aponta-desigualdade-global-entre-generos\/","title":{"rendered":"Relat\u00f3rio aponta desigualdade global entre g\u00eaneros"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www3.weforum.org\/docs\/GGGR2015\/The%20Global%20Gender%20Gap%20Index%202015.pdf\" target=\"_blank\">R<\/a><a href=\"http:\/\/www3.weforum.org\/docs\/GGGR2015\/The%20Global%20Gender%20Gap%20Index%202015.pdf\" target=\"_blank\">elat\u00f3rio de Desigualdade Global de G\u00eanero 2015 <\/a>do F\u00f3rum Econ\u00f4mico Mundial trata das diferen\u00e7as dos g\u00eaneros desde 2006 e aponta que a desigualdade entre homem e mulher, principalmente no mercado de trabalho, ainda \u00e9 grande. Foram pesquisados 145 pa\u00edses.<\/p>\n<p style=\"text-align: justify;\">Segundo o relat\u00f3rio, o sal\u00e1rio da mulher hoje \u00e9 igual a do homem dez anos atr\u00e1s. Ou seja, pode levar 118 anos para que as mulheres ganhem o mesmo sal\u00e1rio do que os homens.<\/p>\n<p style=\"text-align: justify;\">Desde 2006, 250 milh\u00f5es de mulheres passaram a ser parte do mercado de trabalho, com carteira assinada e direitos trabalhistas. Isso porque as mulheres passaram a entrar mais na Universidade do que os homens, em pelo menos cem pa\u00edses.<\/p>\n<p style=\"text-align: justify;\">A Su\u00e9cia e Dinamarca s\u00e3o os pa\u00edses em que as mulheres tiveram mais avan\u00e7os, chegando a ser maiorias em alguns cargos de chefia. Mas o maior avan\u00e7o em quest\u00e3o de sal\u00e1rios iguais e n\u00famero de chefias ocupadas por mulheres \u00e9 a Col\u00f4mbia e a Fran\u00e7a.<\/p>\n<p style=\"text-align: justify;\">No ranking geral de igualdade de g\u00eanero, o Brasil passou de 71\u00aa em 2014 para 85\u00ba lugar. J\u00e1 falando em igualdade salarial, o Brasil cai para o 133\u00ba lugar (de 145 pa\u00edses ao todo).<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-11549-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www2.comunitaria.com.br\/wp-content\/uploads\/2015\/11\/Trocando_em_Miudo_Relatorio_aponta_diferenca_salarial_entre_homens_e_mulheres.mp3?_=1\" \/><a href=\"http:\/\/www2.comunitaria.com.br\/wp-content\/uploads\/2015\/11\/Trocando_em_Miudo_Relatorio_aponta_diferenca_salarial_entre_homens_e_mulheres.mp3\">http:\/\/www2.comunitaria.com.br\/wp-content\/uploads\/2015\/11\/Trocando_em_Miudo_Relatorio_aponta_diferenca_salarial_entre_homens_e_mulheres.mp3<\/a><\/audio>\n<p><strong>\u00c1udio:<\/strong> Radioag\u00eancia Nacional<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Relat\u00f3rio de Desigualdade Global de G\u00eanero 2015 do F\u00f3rum Econ\u00f4mico Mundial trata das diferen\u00e7as dos g\u00eaneros desde 2006 e aponta que a desigualdade entre homem e mulher, principalmente no mercado&#8230;<\/p>","protected":false},"author":2,"featured_media":11551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[51,33],"tags":[2028,451,2029],"class_list":["post-11549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-noticias","tag-desilgualdade-de-genero","tag-mulheres","tag-relatorio-global"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/11549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/comments?post=11549"}],"version-history":[{"count":0,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/posts\/11549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media\/11551"}],"wp:attachment":[{"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/media?parent=11549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/categories?post=11549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.comunitaria.com.br\/en\/wp-json\/wp\/v2\/tags?post=11549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}